{"id":7392,"date":"2013-10-16T17:47:25","date_gmt":"2013-10-16T15:47:25","guid":{"rendered":"http:\/\/micheko.com\/cms\/wp-content\/uploads\/Micheko_Galerie_S_Shirai_cleaning.jpg"},"modified":"2013-10-16T17:47:25","modified_gmt":"2013-10-16T15:47:25","slug":"micheko_galerie_s_shirai_cleaning","status":"inherit","type":"attachment","link":"https:\/\/www.micheko.com\/ja\/%e3%82%a2%e3%83%bc%e3%83%81%e3%82%b9%e3%83%88\/satomi-shirai\/micheko_galerie_s_shirai_cleaning\/","title":{"rendered":"Satomi Shirai, Cleaning"},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"open","template":"","meta":[],"class_list":["post-7392","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a data-rel=\"iLightbox[postimages]\" data-title=\"\" data-caption=\"\" href='https:\/\/www.micheko.com\/wp-content\/uploads\/Micheko_Galerie_S_Shirai_cleaning.jpg'><img decoding=\"async\" width=\"400\" height=\"327\" src=\"https:\/\/www.micheko.com\/wp-content\/uploads\/Micheko_Galerie_S_Shirai_cleaning-400x327.jpg\" class=\"attachment-medium size-medium lazyload\" alt=\"\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27800%27%20height%3D%27654%27%20viewBox%3D%270%200%20800%20654%27%3E%3Crect%20width%3D%27800%27%20height%3D%27654%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/www.micheko.com\/wp-content\/uploads\/Micheko_Galerie_S_Shirai_cleaning-400x327.jpg\" data-srcset=\"https:\/\/www.micheko.com\/wp-content\/uploads\/Micheko_Galerie_S_Shirai_cleaning-200x164.jpg 200w, https:\/\/www.micheko.com\/wp-content\/uploads\/Micheko_Galerie_S_Shirai_cleaning-309x253.jpg 309w, https:\/\/www.micheko.com\/wp-content\/uploads\/Micheko_Galerie_S_Shirai_cleaning-400x327.jpg 400w, https:\/\/www.micheko.com\/wp-content\/uploads\/Micheko_Galerie_S_Shirai_cleaning-600x491.jpg 600w, https:\/\/www.micheko.com\/wp-content\/uploads\/Micheko_Galerie_S_Shirai_cleaning-704x576.jpg 704w, https:\/\/www.micheko.com\/wp-content\/uploads\/Micheko_Galerie_S_Shirai_cleaning.jpg 800w, https:\/\/www.micheko.com\/wp-content\/uploads\/Micheko_Galerie_S_Shirai_cleaning-309x253@2x.jpg 618w\" data-sizes=\"auto\" \/><\/a><\/p>\n<p>Satomi Shirai, Cleaning<\/p>\n"},"caption":{"rendered":"<p>Satomi Shirai, Cleaning<\/p>\n"},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":800,"height":654,"file":"Micheko_Galerie_S_Shirai_cleaning.jpg","sizes":{"thumbnail":{"file":"Micheko_Galerie_S_Shirai_cleaning-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.micheko.com\/wp-content\/uploads\/Micheko_Galerie_S_Shirai_cleaning-150x150.jpg"},"medium":{"file":"Micheko_Galerie_S_Shirai_cleaning-400x327.jpg","width":400,"height":327,"mime_type":"image\/jpeg","source_url":"https:\/\/www.micheko.com\/wp-content\/uploads\/Micheko_Galerie_S_Shirai_cleaning-400x327.jpg"},"large":{"file":"Micheko_Galerie_S_Shirai_cleaning-800x654.jpg","width":800,"height":654,"mime_type":"image\/jpeg","source_url":"https:\/\/www.micheko.com\/wp-content\/uploads\/Micheko_Galerie_S_Shirai_cleaning-800x654.jpg"},"post-news-thumbs":{"file":"Micheko_Galerie_S_Shirai_cleaning-704x576.jpg","width":704,"height":576,"mime_type":"image\/jpeg","source_url":"https:\/\/www.micheko.com\/wp-content\/uploads\/Micheko_Galerie_S_Shirai_cleaning-704x576.jpg"},"ausstellungen":{"file":"Micheko_Galerie_S_Shirai_cleaning-400x270.jpg","width":400,"height":270,"mime_type":"image\/jpeg","source_url":"https:\/\/www.micheko.com\/wp-content\/uploads\/Micheko_Galerie_S_Shirai_cleaning-400x270.jpg"},"testcrop":{"file":"Micheko_Galerie_S_Shirai_cleaning-309x253.jpg","width":309,"height":253,"mime_type":"image\/jpeg","source_url":"https:\/\/www.micheko.com\/wp-content\/uploads\/Micheko_Galerie_S_Shirai_cleaning-309x253.jpg"},"portfolio-full":{"file":"Micheko_Galerie_S_Shirai_cleaning-800x400.jpg","width":800,"height":400,"mime_type":"image\/jpeg","source_url":"https:\/\/www.micheko.com\/wp-content\/uploads\/Micheko_Galerie_S_Shirai_cleaning-800x400.jpg"},"portfolio-one":{"file":"Micheko_Galerie_S_Shirai_cleaning-540x272.jpg","width":540,"height":272,"mime_type":"image\/jpeg","source_url":"https:\/\/www.micheko.com\/wp-content\/uploads\/Micheko_Galerie_S_Shirai_cleaning-540x272.jpg"},"portfolio-two":{"file":"Micheko_Galerie_S_Shirai_cleaning-460x295.jpg","width":460,"height":295,"mime_type":"image\/jpeg","source_url":"https:\/\/www.micheko.com\/wp-content\/uploads\/Micheko_Galerie_S_Shirai_cleaning-460x295.jpg"},"portfolio-three":{"file":"Micheko_Galerie_S_Shirai_cleaning-300x214.jpg","width":300,"height":214,"mime_type":"image\/jpeg","source_url":"https:\/\/www.micheko.com\/wp-content\/uploads\/Micheko_Galerie_S_Shirai_cleaning-300x214.jpg"},"portfolio-five":{"file":"Micheko_Galerie_S_Shirai_cleaning-177x142.jpg","width":177,"height":142,"mime_type":"image\/jpeg","source_url":"https:\/\/www.micheko.com\/wp-content\/uploads\/Micheko_Galerie_S_Shirai_cleaning-177x142.jpg"},"blog-large":{"file":"Micheko_Galerie_S_Shirai_cleaning-669x272.jpg","width":669,"height":272,"mime_type":"image\/jpeg","source_url":"https:\/\/www.micheko.com\/wp-content\/uploads\/Micheko_Galerie_S_Shirai_cleaning-669x272.jpg"},"blog-medium":{"file":"Micheko_Galerie_S_Shirai_cleaning-320x202.jpg","width":320,"height":202,"mime_type":"image\/jpeg","source_url":"https:\/\/www.micheko.com\/wp-content\/uploads\/Micheko_Galerie_S_Shirai_cleaning-320x202.jpg"},"recent-posts":{"file":"Micheko_Galerie_S_Shirai_cleaning-700x441.jpg","width":700,"height":441,"mime_type":"image\/jpeg","source_url":"https:\/\/www.micheko.com\/wp-content\/uploads\/Micheko_Galerie_S_Shirai_cleaning-700x441.jpg"},"recent-works-thumbnail":{"file":"Micheko_Galerie_S_Shirai_cleaning-66x66.jpg","width":66,"height":66,"mime_type":"image\/jpeg","source_url":"https:\/\/www.micheko.com\/wp-content\/uploads\/Micheko_Galerie_S_Shirai_cleaning-66x66.jpg"},"fusion-200":{"file":"Micheko_Galerie_S_Shirai_cleaning-200x164.jpg","width":200,"height":164,"mime_type":"image\/jpeg","source_url":"https:\/\/www.micheko.com\/wp-content\/uploads\/Micheko_Galerie_S_Shirai_cleaning-200x164.jpg"},"fusion-400":{"file":"Micheko_Galerie_S_Shirai_cleaning-400x327.jpg","width":400,"height":327,"mime_type":"image\/jpeg","source_url":"https:\/\/www.micheko.com\/wp-content\/uploads\/Micheko_Galerie_S_Shirai_cleaning-400x327.jpg"},"fusion-600":{"file":"Micheko_Galerie_S_Shirai_cleaning-600x491.jpg","width":600,"height":491,"mime_type":"image\/jpeg","source_url":"https:\/\/www.micheko.com\/wp-content\/uploads\/Micheko_Galerie_S_Shirai_cleaning-600x491.jpg"},"fusion-800":{"file":"Micheko_Galerie_S_Shirai_cleaning-800x654.jpg","width":800,"height":654,"mime_type":"image\/jpeg","source_url":"https:\/\/www.micheko.com\/wp-content\/uploads\/Micheko_Galerie_S_Shirai_cleaning-800x654.jpg"},"full":{"file":"Micheko_Galerie_S_Shirai_cleaning.jpg","width":800,"height":654,"mime_type":"image\/jpeg","source_url":"https:\/\/www.micheko.com\/wp-content\/uploads\/Micheko_Galerie_S_Shirai_cleaning.jpg"}},"image_meta":{"aperture":"0","credit":"Michele Vitucci","camera":"","caption":"","created_timestamp":"0","copyright":"Michele Vitucci","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":1004,"source_url":"https:\/\/www.micheko.com\/wp-content\/uploads\/Micheko_Galerie_S_Shirai_cleaning.jpg","filename":"Micheko_Galerie_S_Shirai_cleaning.jpg","filesize":399093,"_links":{"self":[{"href":"https:\/\/www.micheko.com\/ja\/wp-json\/wp\/v2\/media\/7392","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.micheko.com\/ja\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.micheko.com\/ja\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.micheko.com\/ja\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.micheko.com\/ja\/wp-json\/wp\/v2\/comments?post=7392"}],"wp:attached-to":[{"embeddable":true,"post_type":"page","id":1004,"href":"https:\/\/www.micheko.com\/ja\/wp-json\/wp\/v2\/pages\/1004"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}